{"id":258134,"date":"2026-05-22T10:31:44","date_gmt":"2026-05-22T10:31:44","guid":{"rendered":"https:\/\/kaempff-kohler.lu\/product\/speculoos-tiramisu\/"},"modified":"2026-05-22T10:31:44","modified_gmt":"2026-05-22T10:31:44","slug":"speculoos-tiramisu","status":"publish","type":"product","link":"https:\/\/kaempff-kohler.lu\/en\/product\/speculoos-tiramisu\/","title":{"rendered":"Speculoos Tiramisu"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Order 18h in advance<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n","protected":false},"featured_media":257080,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[198],"product_tag":[],"class_list":{"0":"post-258134","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-jars","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Speculoos Tiramisu - Kaempff-Kohler<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kaempff-kohler.lu\/en\/product\/speculoos-tiramisu\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Speculoos Tiramisu - Kaempff-Kohler\" \/>\n<meta property=\"og:description\" content=\"Order 18h in advance\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kaempff-kohler.lu\/en\/product\/speculoos-tiramisu\/\" \/>\n<meta property=\"og:site_name\" content=\"Kaempff-Kohler\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kaempff.kohler.traiteur\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kaempff-kohler.lu\/wp-content\/uploads\/IMG_8613-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/product\\\/speculoos-tiramisu\\\/\",\"url\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/product\\\/speculoos-tiramisu\\\/\",\"name\":\"Speculoos Tiramisu - Kaempff-Kohler\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/product\\\/speculoos-tiramisu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/product\\\/speculoos-tiramisu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kaempff-kohler.lu\\\/wp-content\\\/uploads\\\/IMG_8613-1-scaled.jpg\",\"datePublished\":\"2026-05-22T10:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/product\\\/speculoos-tiramisu\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/product\\\/speculoos-tiramisu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/product\\\/speculoos-tiramisu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kaempff-kohler.lu\\\/wp-content\\\/uploads\\\/IMG_8613-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/kaempff-kohler.lu\\\/wp-content\\\/uploads\\\/IMG_8613-1-scaled.jpg\",\"width\":1440,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/product\\\/speculoos-tiramisu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Click &amp; Collect\",\"item\":\"https:\\\/\\\/kaempff-kohler.lu\\\/collect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Speculoos Tiramisu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/\",\"name\":\"Kaempff-Kohler\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/#organization\"},\"alternateName\":\"KK\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/#organization\",\"name\":\"Kaempff-Kohler\",\"url\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kaempff-kohler.lu\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo-dark.svg\",\"contentUrl\":\"https:\\\/\\\/kaempff-kohler.lu\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo-dark.svg\",\"width\":1,\"height\":1,\"caption\":\"Kaempff-Kohler\"},\"image\":{\"@id\":\"https:\\\/\\\/kaempff-kohler.lu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kaempff.kohler.traiteur\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Speculoos Tiramisu - Kaempff-Kohler","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kaempff-kohler.lu\/en\/product\/speculoos-tiramisu\/","og_locale":"en_US","og_type":"article","og_title":"Speculoos Tiramisu - Kaempff-Kohler","og_description":"Order 18h in advance","og_url":"https:\/\/kaempff-kohler.lu\/en\/product\/speculoos-tiramisu\/","og_site_name":"Kaempff-Kohler","article_publisher":"https:\/\/www.facebook.com\/kaempff.kohler.traiteur","og_image":[{"width":1440,"height":2560,"url":"https:\/\/kaempff-kohler.lu\/wp-content\/uploads\/IMG_8613-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kaempff-kohler.lu\/en\/product\/speculoos-tiramisu\/","url":"https:\/\/kaempff-kohler.lu\/en\/product\/speculoos-tiramisu\/","name":"Speculoos Tiramisu - Kaempff-Kohler","isPartOf":{"@id":"https:\/\/kaempff-kohler.lu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kaempff-kohler.lu\/en\/product\/speculoos-tiramisu\/#primaryimage"},"image":{"@id":"https:\/\/kaempff-kohler.lu\/en\/product\/speculoos-tiramisu\/#primaryimage"},"thumbnailUrl":"https:\/\/kaempff-kohler.lu\/wp-content\/uploads\/IMG_8613-1-scaled.jpg","datePublished":"2026-05-22T10:31:44+00:00","breadcrumb":{"@id":"https:\/\/kaempff-kohler.lu\/en\/product\/speculoos-tiramisu\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kaempff-kohler.lu\/en\/product\/speculoos-tiramisu\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kaempff-kohler.lu\/en\/product\/speculoos-tiramisu\/#primaryimage","url":"https:\/\/kaempff-kohler.lu\/wp-content\/uploads\/IMG_8613-1-scaled.jpg","contentUrl":"https:\/\/kaempff-kohler.lu\/wp-content\/uploads\/IMG_8613-1-scaled.jpg","width":1440,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/kaempff-kohler.lu\/en\/product\/speculoos-tiramisu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kaempff-kohler.lu\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Click &amp; Collect","item":"https:\/\/kaempff-kohler.lu\/collect\/"},{"@type":"ListItem","position":3,"name":"Speculoos Tiramisu"}]},{"@type":"WebSite","@id":"https:\/\/kaempff-kohler.lu\/en\/#website","url":"https:\/\/kaempff-kohler.lu\/en\/","name":"Kaempff-Kohler","description":"","publisher":{"@id":"https:\/\/kaempff-kohler.lu\/en\/#organization"},"alternateName":"KK","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kaempff-kohler.lu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kaempff-kohler.lu\/en\/#organization","name":"Kaempff-Kohler","url":"https:\/\/kaempff-kohler.lu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kaempff-kohler.lu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/kaempff-kohler.lu\/wp-content\/uploads\/2022\/10\/logo-dark.svg","contentUrl":"https:\/\/kaempff-kohler.lu\/wp-content\/uploads\/2022\/10\/logo-dark.svg","width":1,"height":1,"caption":"Kaempff-Kohler"},"image":{"@id":"https:\/\/kaempff-kohler.lu\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kaempff.kohler.traiteur"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kaempff-kohler.lu\/en\/wp-json\/wp\/v2\/product\/258134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kaempff-kohler.lu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kaempff-kohler.lu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kaempff-kohler.lu\/en\/wp-json\/wp\/v2\/media\/257080"}],"wp:attachment":[{"href":"https:\/\/kaempff-kohler.lu\/en\/wp-json\/wp\/v2\/media?parent=258134"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kaempff-kohler.lu\/en\/wp-json\/wp\/v2\/product_brand?post=258134"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kaempff-kohler.lu\/en\/wp-json\/wp\/v2\/product_cat?post=258134"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kaempff-kohler.lu\/en\/wp-json\/wp\/v2\/product_tag?post=258134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}